{"id":3489,"date":"2018-11-30T06:03:04","date_gmt":"2018-11-30T05:03:04","guid":{"rendered":"https:\/\/10jourssansecrans.org\/contactenos\/?lang=es"},"modified":"2023-10-24T10:55:15","modified_gmt":"2023-10-24T08:55:15","slug":"contactenos","status":"publish","type":"page","link":"https:\/\/10jourssansecrans.org\/es\/contactenos\/","title":{"rendered":"Cont\u00e1ctenos"},"content":{"rendered":"<p><div class=\"et_d4_element et_pb_section et_pb_section_0  et_pb_css_mix_blend_mode et_pb_fullwidth_section et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<section class=\"et_pb_module et_d4_element et_pb_fullwidth_header et_pb_fullwidth_header_0  et_pb_css_mix_blend_mode et_pb_text_align_left et_pb_bg_layout_dark\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_fullwidth_header_container left\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"et_pb_fullwidth_header_overlay\"><\/div>\n\t\t\t\t<div class=\"et_pb_fullwidth_header_scroll\"><\/div>\n\t\t\t<\/section>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_1  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_0  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_3_5 et_pb_column et_pb_column_0  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<div id=\"et_pb_contact_form_0\" class=\"et_pb_module et_d4_element et_pb_contact_form_0 et_pb_recaptcha_enabled et_pb_contact_form_container clearfix et_block_module\" data-form_unique_num=\"0\" data-form_unique_id=\"30267450-ffd5-4236-8ada-4781df03abf8\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et-pb-contact-message\"><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_contact\">\n\t\t\t\t\t<form class=\"et_pb_contact_form clearfix\" method=\"post\" action=\"https:\/\/10jourssansecrans.org\/es\/wp-json\/wp\/v2\/pages\/3489\">\n\t\t\t\t\t\t<p class=\"et_d4_element et_pb_contact_field et_pb_contact_field_0 et_pb_contact_field_half\" data-id=\"name\" data-type=\"input\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<label for=\"et_pb_contact_name_0\" class=\"et_pb_contact_form_label\">Nombre<\/label>\n\t\t\t\t<input type=\"text\" id=\"et_pb_contact_name_0\" class=\"input\" value=\"\" name=\"et_pb_contact_name_0\" data-required_mark=\"required\" data-field_type=\"input\" data-original_id=\"name\" placeholder=\"Nombre\">\n\t\t\t<\/p><p class=\"et_d4_element et_pb_contact_field et_pb_contact_field_1 et_pb_contact_field_half et_pb_contact_field_last\" data-id=\"email\" data-type=\"email\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<label for=\"et_pb_contact_email_0\" class=\"et_pb_contact_form_label\">Adresse e-mail<\/label>\n\t\t\t\t<input type=\"text\" id=\"et_pb_contact_email_0\" class=\"input\" value=\"\" name=\"et_pb_contact_email_0\" data-required_mark=\"required\" data-field_type=\"email\" data-original_id=\"email\" placeholder=\"Adresse e-mail\">\n\t\t\t<\/p><p class=\"et_d4_element et_pb_contact_field et_pb_contact_field_2 et_pb_contact_field_last\" data-id=\"message\" data-type=\"text\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<label for=\"et_pb_contact_message_0\" class=\"et_pb_contact_form_label\">Message<\/label>\n\t\t\t\t<textarea name=\"et_pb_contact_message_0\" id=\"et_pb_contact_message_0\" class=\"et_pb_contact_message input\" data-required_mark=\"required\" data-field_type=\"text\" data-original_id=\"message\" placeholder=\"Message\"><\/textarea>\n\t\t\t<\/p>\n\t\t\t\t\t\t<input type=\"hidden\" value=\"et_contact_proccess\" name=\"et_pb_contactform_submit_0\"\/>\n\t\t\t\t\t\t<div class=\"et_contact_bottom_container\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<button type=\"submit\" name=\"et_builder_submit_button\" class=\"et_pb_contact_submit et_pb_button\">Envier<\/button>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<input type=\"hidden\" id=\"_wpnonce-et-pb-contact-form-submitted-0\" name=\"_wpnonce-et-pb-contact-form-submitted-0\" value=\"fc8c186f8c\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/3489\" \/>\n\t\t\t\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_2_5 et_pb_column et_pb_column_1  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3>Info<\/h3>\n<p>El objetivo de la asociaci\u00f3n es promover el DESAF\u00cdO DE 10 D\u00cdAS SIN PANTALLAS con guarder\u00edas, guarder\u00edas y escuelas primarias, escuelas intermedias y secundarias, asociaciones, municipios, funcionarios electos, as\u00ed como todos organismos que trabajan a favor de la primera infancia, la infancia o la adolescencia.<\/p>\n<p><strong>D<\/strong><strong>irecci\u00f3n:<\/strong> Elkarteen etxea, 11 Glain Etorbidea, 64 100 BAIONA<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-3489","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/10jourssansecrans.org\/es\/wp-json\/wp\/v2\/pages\/3489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/10jourssansecrans.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/10jourssansecrans.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/10jourssansecrans.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/10jourssansecrans.org\/es\/wp-json\/wp\/v2\/comments?post=3489"}],"version-history":[{"count":8,"href":"https:\/\/10jourssansecrans.org\/es\/wp-json\/wp\/v2\/pages\/3489\/revisions"}],"predecessor-version":[{"id":5068,"href":"https:\/\/10jourssansecrans.org\/es\/wp-json\/wp\/v2\/pages\/3489\/revisions\/5068"}],"wp:attachment":[{"href":"https:\/\/10jourssansecrans.org\/es\/wp-json\/wp\/v2\/media?parent=3489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}