{"id":4944,"date":"2023-08-01T09:08:06","date_gmt":"2023-08-01T07:08:06","guid":{"rendered":"https:\/\/10jourssansecrans.org\/2023\/08\/ne-laissons-pas-les-ecrans-faire-ecran\/"},"modified":"2023-09-18T17:48:35","modified_gmt":"2023-09-18T15:48:35","slug":"ne-laissons-pas-les-ecrans-faire-ecran","status":"publish","type":"post","link":"https:\/\/10jourssansecrans.org\/en\/2023\/08\/ne-laissons-pas-les-ecrans-faire-ecran\/","title":{"rendered":"Ne laissons pas les \u00e9crans faire \u00e9cran !"},"content":{"rendered":"<p>Tel est le slogan de la campagne de pr\u00e9vention initi\u00e9e en Belgique par la F\u00e9d\u00e9ration Wallonie Bruxelles, Yapaka, qui \u0153uvre depuis 1998 pour la pr\u00e9vention de la maltraitance.<\/p>\n<p>Cette campagne a pour objet de <strong>sensibiliser \u00e0 la place des \u00e9crans dans les relations parents\/enfants<\/strong>, tout en valorisant le plaisir de moments partag\u00e9s en famille. Elle inclut notamment la diffusion de 4 spots dans les \u00e9crans publicitaires sur les chaines TV belges, d\u2019affiches et posters adapt\u00e9s aux tranches d\u2019\u00e2ges des enfants (3-6-9-12).<\/p>\n<p>Si les \u00e9crans font d\u00e9sormais partie de notre quotidien, pour des usages professionnels, administratifs, personnels, familiaux et am\u00e8nent des solutions facilitant nos vies, ils peuvent facilement prendre toute la place, faire \u00e9cran \u00e0 la relation parent\/enfant, adulte\/enfant, du fait des interruptions r\u00e9p\u00e9t\u00e9es dans la relation : les chercheurs parlent de technof\u00e9rence.<\/p>\n<h2><\/h2>\n<h2><strong>Technof\u00e9rence et effets sur la construction des enfants<\/strong><\/h2>\n<p>Ce ph\u00e9nom\u00e8ne nouveau d\u00e9signe les <strong>multiples interruptions quotidiennes dans les interactions, les relations, dues \u00e0 la pr\u00e9sence d\u2019outils technologiques<\/strong>, en particulier les smartphones.<\/p>\n<p>La technof\u00e9rence devient source d\u2019inqui\u00e9tude lorsqu\u2019elle prend une grande place dans le quotidien partag\u00e9 avec les enfants\u00a0: des professionnels de l\u2019accueil des tous petits questionnent la place des \u00e9crans comme un <strong>\u00e9l\u00e9ment de sant\u00e9 publique<\/strong>.<\/p>\n<p>Ils font en effet le constat d\u2019enfants en \u00e9tat de grande fatigue, pr\u00e9sentant des retards dans le d\u00e9veloppement langagier, des difficult\u00e9s \u00e0 \u00eatre en relation, \u00e0 se concentrer, \u00e0 se mouvoir dans l\u2019espace. Les enfants, notamment les b\u00e9b\u00e9s, se construisent en lien avec l\u2019adulte. Ils ont besoin pour grandir, d\u2019une pr\u00e9sence attentive et continue du parent\/adulte, qui s\u2019ajuste \u00e0 leurs besoins et \u00e9motions.<\/p>\n<p>Or, des chercheurs ont montr\u00e9 qu\u2019un adulte consultant son smartphone en pr\u00e9sence d\u2019un enfant s\u2019adresse moins \u00e0 lui, lui parle moins, utilise moins de vocabulaire; l\u2019enfant parle moins \u00e9galement.<\/p>\n<p>Les interf\u00e9rences r\u00e9p\u00e9t\u00e9es<strong> rompent le lien et appauvrissent les relations enfant\/adulte<\/strong>, ce qui a des impacts sur l\u2019enfant aux plans neurologique, affectif, cognitif, notamment au niveau du langage, de l\u2019estime de soi, de la construction identitaire.<\/p>\n<p>Par exemple, lorsque l\u2019adulte regarde son t\u00e9l\u00e9phone, il est absent psychiquement. Son visage, capt\u00e9 par l\u2019ext\u00e9rieur, devient froid, impassible, son regard est centr\u00e9 sur l\u2019\u00e9cran et le lien de regard est coup\u00e9.<\/p>\n<p>Or, le b\u00e9b\u00e9 ne sait pas interpr\u00e9ter cette absence. Il se trouve face \u00e0 un vide interactif et, si les \u00e9crans sont omnipr\u00e9sents et les interruptions r\u00e9p\u00e9t\u00e9es, la relation peut m\u00eame \u00eatre v\u00e9cue comme angoissante, voire entra\u00eener le d\u00e9veloppement d\u2019un sentiment d\u2019abandon.<\/p>\n<p>De plus, si le parent r\u00e9pond toujours aux notifications, le tout petit peut int\u00e9grer le fait que l\u2019ext\u00e9rieur a plus d\u2019importance et de valeur que lui et assimiler une culture de l\u2019imm\u00e9diatet\u00e9, de l\u2019\u00e9parpillement.<\/p>\n<div id=\"attachment_3442\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3442\" class=\"wp-image-3442 size-medium\" src=\"https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2023\/07\/PHOTO-MAIN-BB-ADULTE-300x203.jpg\" alt=\"B\u00e9b\u00e9 qui tient le doigt d'un adulte\" width=\"300\" height=\"203\" \/><p id=\"caption-attachment-3442\" class=\"wp-caption-text\">l&#8217;importance du lien pour le b\u00e9b\u00e9<\/p><\/div>\n<h2><\/h2>\n<h2><strong>Penser notre lien \u00e0 la technologie<\/strong><\/h2>\n<p>La campagne men\u00e9e par Yapaka a donc pour objet d<strong>\u2019interroger la place que nous donnons aux \u00e9crans<\/strong> quand nous sommes avec nos enfants, l\u2019impact des interf\u00e9rences dans les liens parents\/enfants et professionnels\/enfants, ainsi que les traces sur le d\u00e9veloppement des plus jeunes.<\/p>\n<p>Penser notre lien \u00e0 la technologie permet une <strong>prise de conscience de nos usages<\/strong>, et donc une <strong>prise de distance<\/strong> face \u00e0 des comportements automatiques.<\/p>\n<p>Chacun peut alors trouver des astuces pour limiter les interf\u00e9rences dans le lien avec l\u2019enfant\u00a0: consulter son smartphone une fois l\u2019enfant couch\u00e9, enlever les notifications, notamment lors des moments d\u2019\u00e9change comme les repas, garder le t\u00e9l\u00e9phone \u00e0\u00a0distance pendant les moments de nursing, de jeu.<\/p>\n<p>Les \u00e9crans sont \u00e9galement pr\u00e9sents dans la sph\u00e8re professionnelle, et leur impact pose question notamment dans le domaine de la petite enfance. Des interruptions fr\u00e9quentes font en effet exp\u00e9rimenter \u00e0 l\u2019enfant une relation dispers\u00e9e et d\u00e9tourn\u00e9e au profit d\u2019un enjeu ext\u00e9rieur.<\/p>\n<p>Comment maintenir un espace de concentration et de disponibilit\u00e9, une relation soutenue et bienveillante, comment exiger d\u2019eux une concentration sans faille, si la relation est interrompue par un \u00e9cran ?<\/p>\n<p>&nbsp;<\/p>\n<p>Que ce soit dans le domaine familial ou professionnel, l\u2019utilisation des \u00e9crans doit \u00eatre pens\u00e9e, afin qu\u2019ils ne prennent pas toute la place et n\u2019\u00e9branlent pas les adultes dans le r\u00f4le qu\u2019ils ont \u00e0 jouer dans le d\u00e9veloppement cognitif, social, affectif et comportemental des enfants.<\/p>\n<p>&nbsp;<\/p>\n<p>Voici des liens pour aller plus loin sur cette campagne de pr\u00e9vention et sur la notion de technof\u00e9rence :<\/p>\n<p><a href=\"https:\/\/www.yapaka.be\/campagne\/campagne-ne-laissons-pas-les-ecrans-faire-ecran\">https:\/\/www.yapaka.be\/campagne\/campagne-ne-laissons-pas-les-ecrans-faire-ecran<\/a><\/p>\n<p><a href=\"https:\/\/www.yapaka.be\/texte\/texte-ne-laissons-pas-les-ecrans-faire-ecran\">https:\/\/www.yapaka.be\/texte\/texte-ne-laissons-pas-les-ecrans-faire-ecran<\/a><\/p>\n<p><a href=\"https:\/\/www.yapaka.be\/page\/la-coordination-de-la-prevention-de-la-maltraitance\">https:\/\/www.yapaka.be\/page\/la-coordination-de-la-prevention-de-la-maltraitance<\/a><\/p>\n<p><a href=\"https:\/\/www.yapaka.be\/page\/spots-tv-diffusion-de-4-spots-ne-laissons-pas-les-ecrans-faire-ecran\">[Spots TV] Diffusion de 4 spots &#8220;Ne laissons pas les \u00e9crans faire \u00e9cran&#8221; | Yapaka<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tel est le slogan de la campagne de pr\u00e9vention initi\u00e9e en Belgique par la F\u00e9d\u00e9ration Wallonie Bruxelles, Yapaka, qui \u0153uvre depuis 1998 pour la pr\u00e9vention de la maltraitance. Cette campagne [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":4577,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[],"class_list":["post-4944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jeunes-et-ecrans-en"],"_links":{"self":[{"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/posts\/4944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/comments?post=4944"}],"version-history":[{"count":1,"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/posts\/4944\/revisions"}],"predecessor-version":[{"id":4947,"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/posts\/4944\/revisions\/4947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/media\/4577"}],"wp:attachment":[{"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/media?parent=4944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/categories?post=4944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/tags?post=4944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}