{"id":4589,"date":"2019-05-16T07:51:34","date_gmt":"2019-05-16T05:51:34","guid":{"rendered":"https:\/\/10jourssansecrans.org\/harrera\/"},"modified":"2023-09-18T17:30:59","modified_gmt":"2023-09-18T15:30:59","slug":"harrera","status":"publish","type":"page","link":"https:\/\/10jourssansecrans.org\/en\/","title":{"rendered":"Accueil"},"content":{"rendered":"<p><div class=\"et_d4_element et_pb_section et_pb_section_0  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_0  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_0  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_slider et_pb_slider_0 et_pb_slider_fullwidth_off\">\n\t\t\t\t<div class=\"et_pb_slides\">\n\t\t\t\t\t<div class=\"et_d4_element et_pb_slide et_pb_slide_0  et_pb_css_mix_blend_mode et_pb_bg_layout_dark et_pb_slide_with_image et_pb_media_alignment_center et-pb-active-slide\" data-slide-id=\"et_pb_slide_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_container clearfix\">\n\t\t\t\t\t<div class=\"et_pb_slider_container_inner\">\n\t\t\t\t\t\t<div class=\"et_pb_slide_image\"><img loading=\"lazy\" decoding=\"async\" width=\"2119\" height=\"1413\" src=\"https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/08\/enfants-10jourssansecrans.jpg\" alt=\"\" srcset=\"https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/08\/enfants-10jourssansecrans.jpg 2119w, https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/08\/enfants-10jourssansecrans-300x200.jpg 300w, https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/08\/enfants-10jourssansecrans-768x512.jpg 768w, https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/08\/enfants-10jourssansecrans-1024x683.jpg 1024w, https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/08\/enfants-10jourssansecrans-610x407.jpg 610w, https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/08\/enfants-10jourssansecrans-1080x720.jpg 1080w\" sizes=\"(max-width: 2119px) 100vw, 2119px\" class=\"wp-image-731\" \/><\/div>\n\t\t\t\t\t\t<div class=\"et_pb_slide_description\">\n\t\t\t\t\t\t\t<h2 class=\"et_pb_slide_title\">10 days without leisure screens<\/h2><div class=\"et_pb_slide_content\"><p>T\u00e9l\u00e9visions, jeux-vid\u00e9os, consoles, tablettes et smartphones, des milliers d'enfants et d'adolescents\u00a0 vont d\u00e9cider de se d\u00e9connecter des \u00e9crans de loisirs pour les remplacer par des activit\u00e9s de d\u00e9couverte et de rencontre.<\/p><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"et_d4_element et_pb_slide et_pb_slide_1  et_pb_css_mix_blend_mode et_pb_bg_layout_dark et_pb_slide_with_image et_pb_media_alignment_center\" data-slide-id=\"et_pb_slide_1\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_container clearfix\">\n\t\t\t\t\t<div class=\"et_pb_slider_container_inner\">\n\t\t\t\t\t\t<div class=\"et_pb_slide_image\"><img loading=\"lazy\" decoding=\"async\" width=\"648\" height=\"323\" src=\"https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/08\/istock_kids_stem.jpg\" alt=\"\" srcset=\"https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/08\/istock_kids_stem.jpg 648w, https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/08\/istock_kids_stem-480x239.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 648px, 100vw\" class=\"wp-image-746\" \/><\/div>\n\t\t\t\t\t\t<div class=\"et_pb_slide_description\">\n\t\t\t\t\t\t\t<h2 class=\"et_pb_slide_title\">10 days to see the world differently<\/h2><div class=\"et_pb_slide_content\"><p>Un \u00e9v\u00e9nement qui a pour objectif de faire vivre \u00e0 tous les acteurs d\u2019un \u00e9tablissement scolaire (personnel et enseignants compris) et aux familles qui le souhaitent, un moment convivial, voire festif, de r\u00e9flexion et de prise de recul sur l\u2019usage que nous avons tous des \u00e9crans et des outils connect\u00e9s.<\/p><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"et_d4_element et_pb_slide et_pb_slide_2  et_pb_css_mix_blend_mode et_pb_bg_layout_dark et_pb_slide_with_image et_pb_media_alignment_center\" data-slide-id=\"et_pb_slide_2\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_container clearfix\">\n\t\t\t\t\t<div class=\"et_pb_slider_container_inner\">\n\t\t\t\t\t\t<div class=\"et_pb_slide_image\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"371\" src=\"https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/03\/adolescents-10jourssansecrans.jpg\" alt=\"\" srcset=\"https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/03\/adolescents-10jourssansecrans.jpg 660w, https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/03\/adolescents-10jourssansecrans-300x169.jpg 300w, https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2019\/03\/adolescents-10jourssansecrans-610x343.jpg 610w\" sizes=\"(max-width: 660px) 100vw, 660px\" class=\"wp-image-412\" \/><\/div>\n\t\t\t\t\t\t<div class=\"et_pb_slide_description\">\n\t\t\t\t\t\t\t<h2 class=\"et_pb_slide_title\">A major education issue<\/h2><div class=\"et_pb_slide_content\"><p>Pr\u00e9parer les enfants et les adolescents \u00e0 se servir des outils num\u00e9riques sans se laisser asservir. \u00c9coles, familles, professionnels de la sant\u00e9 et de l\u2019\u00e9ducation, et municipalit\u00e9s se mobilisent collectivement pour un enjeu majeur d\u2019\u00e9ducation du 21\u00e8me si\u00e8cle.<\/p><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_1 et_pb_with_background  et_pb_css_mix_blend_mode et_pb_fullwidth_section et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<section class=\"et_pb_module et_d4_element et_pb_fullwidth_header et_pb_fullwidth_header_0  et_pb_css_mix_blend_mode et_pb_text_align_center et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_fullwidth_header_container center\">\n\t\t\t\t\t<div class=\"header-content-container center\">\n\t\t\t\t\t<div class=\"header-content\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<h1 class=\"et_pb_module_header\">The question of time spent in front of screens is at the heart of current educational challenges<\/h1>\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"et_pb_header_content_wrapper\"><\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"et_pb_fullwidth_header_overlay\"><\/div>\n\t\t\t\t<div class=\"et_pb_fullwidth_header_scroll\"><\/div>\n\t\t\t<\/section>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_2  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_1  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_4 et_pb_column et_pb_column_1  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_0  et_pb_text_align_center  et_pb_blurb_position_top et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon et-pb-icon-circle\">\ue030<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h4 class=\"et_pb_module_header\"><span>Living together and citizenship<\/span><\/h4>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><p style=\"text-align: center;\">R\u00e9duction de la violence physique et verbale. Retomb\u00e9es r\u00e9elles sur le climat scolaire et le resserrement des liens familiaux.<\/p><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_4 et_pb_column et_pb_column_2  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_1  et_pb_text_align_center  et_pb_blurb_position_top et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon et-pb-icon-circle\">N<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h2 class=\"et_pb_module_header\"><span>Health and wellbeing<\/span><\/h2>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><p style=\"margin-bottom: 0cm;\">Sant\u00e9 physique et sant\u00e9 mentale, d\u00e9veloppement, sommeil, estime de soi, pr\u00e9vention de l\u2019ob\u00e9sit\u00e9 et des difficult\u00e9s d\u2019apprentissages.<\/p><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_4 et_pb_column et_pb_column_3  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_with_border et_pb_module et_d4_element et_pb_blurb et_pb_blurb_2  et_pb_text_align_center  et_pb_blurb_position_top et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon et-pb-icon-circle et-pb-icon-circle-border\">\ue0e3<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h2 class=\"et_pb_module_header\"><span>Environment and consumption<\/span><\/h2>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><p style=\"margin-bottom: 0cm;\">Le d\u00e9fi est un exercice de consommation responsable, et il permet de r\u00e9duire la sollicitation publicitaire.<\/p><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_4 et_pb_column et_pb_column_4  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_3  et_pb_text_align_center  et_pb_blurb_position_top et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon et-pb-icon-circle\">\ue00f<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h2 class=\"et_pb_module_header\"><span>Media and information education<\/span><\/h2>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><p style=\"margin-bottom: 0cm;\">Permettre aux jeunes de mieux contr\u00f4ler la technologie, et de mieux d\u00e9limiter la fronti\u00e8re qui s\u00e9pare les \u00e9crans qui rendent service des \u00e9crans qui asservissent.<\/p><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_5  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_slider et_pb_slider_1 et_animated et_pb_slider_fullwidth_off et_pb_slider_no_arrows et_pb_slider_no_pagination\">\n\t\t\t\t<div class=\"et_pb_slides\">\n\t\t\t\t\t<div class=\"et_d4_element et_pb_slide et_pb_slide_3  et_pb_css_mix_blend_mode et_pb_bg_layout_light et_pb_media_alignment_center et-pb-active-slide\" data-slide-id=\"et_pb_slide_3\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_container clearfix\">\n\t\t\t\t\t<div class=\"et_pb_slider_container_inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"et_pb_slide_description\">\n\t\t\t\t\t\t\t<h1 class=\"et_pb_slide_title\">A collective challenge<\/h1><div class=\"et_pb_slide_content\"><p>Du <b>7<\/b><b> au <\/b><b>16<\/b><b> juin<\/b><b> 20<\/b><b>2<\/b><b>2<\/b>, des milliers de jeunes vont relever le d\u00e9fi aux m\u00eames dates\u00a0!<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p><\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_6  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_cta_0 et_pb_promo  et_pb_text_align_center et_pb_bg_layout_dark\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_promo_description\"><h2 class=\"et_pb_module_header\">A growing challenge<\/h2><div><p>Alors que le temps d\u2019exposition aux \u00e9crans progresse d\u2019ann\u00e9e en ann\u00e9e et que l\u2019\u00e9quipement des foyers a explos\u00e9, le D\u00c9FI 10 JOURS SANS \u00c9CRANS prennent de l\u2019ampleur chaque ann\u00e9e. Les cr\u00e8ches, coll\u00e8ges, ou \u00e9coles, parents d'\u00e9l\u00e8ves, professionnels de la sant\u00e9 et de l\u2019\u00e9ducation, associations, m\u00e9diath\u00e8ques, particuliers, \u00e9lus, artistes, les acteurs de l\u2019\u00e9ducation unissent leurs efforts pour une mobilisation soci\u00e9tale d\u2019envergure dans d\u00e9marche d\u2019\u00e9ducation populaire.<\/p><\/div><\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_3  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_7  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_blog_0  et_pb_css_mix_blend_mode et_pb_blog_grid_wrapper et_pb_bg_layout_light\">\n\t\t\t\t\t<div class=\"et_pb_blog_grid clearfix \">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"et_pb_ajax_pagination_container\">\n\t\t\t\t\t\t<div class=\"et_pb_salvattore_content\" data-columns>\n\t\t\t<article id=\"post-4938\" class=\"et_pb_post clearfix et_pb_blog_item_0_0 post-4938 post type-post status-publish format-standard has-post-thumbnail hentry category-jeunes-et-ecrans-en\">\n\n\t\t\t\t<div class=\"et_pb_image_container\"><a href=\"https:\/\/10jourssansecrans.org\/en\/2023\/08\/le-defi-10-jours-sans-ecrans-2024-debute-bientot\/\" class=\"entry-featured-image-url\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2023\/08\/PHOTO-BADGES-POUR-ARTICLE-ECHEANCIER-2024-400x250.jpg\" alt=\"Le d\u00e9fi 10 jours sans \u00e9crans 2024 d\u00e9bute bient\u00f4t !\" class=\"\" srcset=\"https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2023\/08\/PHOTO-BADGES-POUR-ARTICLE-ECHEANCIER-2024.jpg 479w, https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2023\/08\/PHOTO-BADGES-POUR-ARTICLE-ECHEANCIER-2024-400x250.jpg 480w \" sizes=\"(max-width:479px) 479px, 100vw \"  width=\"400\" height=\"250\" \/><\/a><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/10jourssansecrans.org\/en\/2023\/08\/le-defi-10-jours-sans-ecrans-2024-debute-bientot\/\">Le d\u00e9fi 10 jours sans \u00e9crans 2024 d\u00e9bute bient\u00f4t !<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t<p class=\"post-meta\">by <span class=\"author vcard\"><a href=\"https:\/\/10jourssansecrans.org\/en\/author\/c-aufildesmots\/\" title=\"Posts by C\u00e9cile Au Fil des Mots\" rel=\"author\">C\u00e9cile Au Fil des Mots<\/a><\/span> | <span class=\"published\">Aug 25, 2023<\/span> | <a href=\"https:\/\/10jourssansecrans.org\/en\/category\/jeunes-et-ecrans-en\/\" rel=\"tag\">Jeunes et \u00e9crans<\/a><\/p><div class=\"post-content\"><div class=\"post-content-inner\"><p>Vous avez envie de participer au d\u00e9fi 10 jours sans \u00e9crans\u00a0et vous vous posez des questions par rapport \u00e0 l\u2019organisation, le planning, l\u2019accompagnement\u00a0?  &nbsp; Nous vous proposons ici un \u00e9ch\u00e9ancier pr\u00e9visionnel des mois,...<\/p>\n<\/div><\/div>\t\t\t\n\t\t\t<\/article>\n\t\t\t\t\n\t\t\t<article id=\"post-4944\" class=\"et_pb_post clearfix et_pb_blog_item_0_1 post-4944 post type-post status-publish format-standard has-post-thumbnail hentry category-jeunes-et-ecrans-en\">\n\n\t\t\t\t<div class=\"et_pb_image_container\"><a href=\"https:\/\/10jourssansecrans.org\/en\/2023\/08\/ne-laissons-pas-les-ecrans-faire-ecran\/\" class=\"entry-featured-image-url\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2023\/07\/PHOTO-MAIN-BB-ADULTE-400x250.jpg\" alt=\"Ne laissons pas les \u00e9crans faire \u00e9cran !\" class=\"\" srcset=\"https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2023\/07\/PHOTO-MAIN-BB-ADULTE.jpg 479w, https:\/\/10jourssansecrans.org\/wp-content\/uploads\/2023\/07\/PHOTO-MAIN-BB-ADULTE-400x250.jpg 480w \" sizes=\"(max-width:479px) 479px, 100vw \"  width=\"400\" height=\"250\" \/><\/a><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/10jourssansecrans.org\/en\/2023\/08\/ne-laissons-pas-les-ecrans-faire-ecran\/\">Ne laissons pas les \u00e9crans faire \u00e9cran !<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t<p class=\"post-meta\">by <span class=\"author vcard\"><a href=\"https:\/\/10jourssansecrans.org\/en\/author\/c-aufildesmots\/\" title=\"Posts by C\u00e9cile Au Fil des Mots\" rel=\"author\">C\u00e9cile Au Fil des Mots<\/a><\/span> | <span class=\"published\">Aug 1, 2023<\/span> | <a href=\"https:\/\/10jourssansecrans.org\/en\/category\/jeunes-et-ecrans-en\/\" rel=\"tag\">Jeunes et \u00e9crans<\/a><\/p><div class=\"post-content\"><div class=\"post-content-inner\"><p>Tel est le slogan de la campagne de pr\u00e9vention initi\u00e9e en Belgique par la F\u00e9d\u00e9ration Wallonie Bruxelles, Yapaka, qui \u0153uvre depuis 1998 pour la pr\u00e9vention de la maltraitance. Cette campagne a pour objet de sensibiliser \u00e0 la place des \u00e9crans dans les relations...<\/p>\n<\/div><\/div>\t\t\t\n\t\t\t<\/article>\n\t\t\t\t\n\t\t\t<article id=\"post-3578\" class=\"et_pb_post clearfix et_pb_no_thumb et_pb_blog_item_0_2 post-3578 post type-post status-publish format-link hentry post_format-post-format-link\">\n\n\t\t\t\t<div class=\"et_link_content et_pb_text_color_light\">\n                        <h2><a href=\"https:\/\/10jourssansecrans.org\/en\/2020\/05\/droits-des-mineurs-et-monde-numerique\/\">Droits des mineurs et monde num\u00e9rique<\/a><\/h2>\n                        <a href=\"https:\/\/10jourssansecrans.org\/en\/2020\/05\/droits-des-mineurs-et-monde-numerique\/\" class=\"et_link_main_url\">https:\/\/10jourssansecrans.org\/en\/2020\/05\/droits-des-mineurs-et-monde-numerique\/<\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<p class=\"post-meta\">by <span class=\"author vcard\"><a href=\"https:\/\/10jourssansecrans.org\/en\/author\/eneko\/\" title=\"Posts by Eneko\" rel=\"author\">Eneko<\/a><\/span> | <span class=\"published\">May 27, 2020<\/span> | <\/p><div class=\"post-content\"><div class=\"post-content-inner\"><p>Plus que quelques jours pour participer \u00e0 la consultation publique de la CNIL au sujet des droits des mineurs dans l'environnement num\u00e9rique.Le 21 avril dernier et jusqu'au premier juin prochain, la Commission Nationale de l'Informatique et des libert\u00e9s a lanc\u00e9 une...<\/p>\n<\/div><\/div>\t\t\t\n\t\t\t<\/article>\n\t\t\t\t\n\t\t\t<article id=\"post-3567\" class=\"et_pb_post clearfix et_pb_no_thumb et_pb_blog_item_0_3 post-3567 post type-post status-publish format-standard hentry\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"entry-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/10jourssansecrans.org\/en\/2020\/03\/70-easy-ideas-for-playing-with-kids-indoors\/\">70 easy ideas for playing with kids indoors<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t<p class=\"post-meta\">by <span class=\"author vcard\"><a href=\"https:\/\/10jourssansecrans.org\/en\/author\/eneko\/\" title=\"Posts by Eneko\" rel=\"author\">Eneko<\/a><\/span> | <span class=\"published\">Mar 18, 2020<\/span> | <\/p><div class=\"post-content\"><div class=\"post-content-inner\"><p>Confinement is an opportunity for parents to rethink the time they will spend with their children. The digital entertainment industry is already ready to take the opportunity to capture as much of this available attention as possible. The vast majority of parents want...<\/p>\n<\/div><\/div>\t\t\t\n\t\t\t<\/article>\n\t\t\t\t<\/div><div><div class=\"pagination clearfix\">\n\t<div class=\"alignleft\"><\/div>\n\t<div class=\"alignright\"><\/div>\n<\/div><\/div><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t \n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_4  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_8  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><iframe loading=\"lazy\" width=\"100%\" height=\"600px\" src=\"https:\/\/2b745f93.sibforms.com\/serve\/MUIEADe3a5N-hyOrAy2aLe8OHMRlcN8HYN4H0qm7Wna73WbMrF8zAv-Ys2y9Aj0u4m3_rVHd2ELd_jt3wRqbvNwFnta5SN6GU_aCzfBQqplsFqHv-5_YllNe691SorxpPWR2VAL3zuCGJAkFoQOiotwLdyKMlHGEOoxYqB4JRKfBvSPnaey4CB2KOg3w9vbtL1NHon4bn071X8L1\" frameborder=\"0\" scrolling=\"auto\" allowfullscreen style=\"display: block;margin-left: auto;margin-right: auto;max-width: 100%;\"><\/iframe><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Fran\u00e7ais) D\u00e9fi 10 Jours sans \u00e9crans. Du 7 au 16 juin 2022, t\u00e9l\u00e9visions, jeux vid\u00e9os, consoles, tablettes et smartphones, des milliers d\u2019enfants et d\u2019adolescents vont d\u00e9cider de se d\u00e9connecter des \u00e9crans r\u00e9cr\u00e9atifs pendant dix jours pour les remplacer par des activit\u00e9s de d\u00e9couverte et de rencontre.<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"[et_pb_section bb_built=\"1\"][et_pb_row][et_pb_column type=\"4_4\"][\/et_pb_column][\/et_pb_row][\/et_pb_section]","_et_gb_content_width":"","footnotes":""},"class_list":["post-4589","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/pages\/4589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/comments?post=4589"}],"version-history":[{"count":9,"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/pages\/4589\/revisions"}],"predecessor-version":[{"id":4935,"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/pages\/4589\/revisions\/4935"}],"wp:attachment":[{"href":"https:\/\/10jourssansecrans.org\/en\/wp-json\/wp\/v2\/media?parent=4589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}